{"id":1640,"date":"2020-09-23T15:07:36","date_gmt":"2020-09-23T15:07:36","guid":{"rendered":"http:\/\/europipeline-equipment.com\/sito\/?p=1640"},"modified":"2021-05-17T15:02:52","modified_gmt":"2021-05-17T15:02:52","slug":"pipeline-equipment-available","status":"publish","type":"post","link":"https:\/\/www.europipeline-equipment.com\/sito\/pipeline-equipment-available\/","title":{"rendered":"PIPELINE EQUIPMENT AVAILABLE!"},"content":{"rendered":"<p>Europipeline Group has always available some pieces of pipeline equipment in stock. Check out the list and see if something matches your site needs!<\/p>\n<ul>\n<li>n\u00b0 2 FP120 mechanical pipelayers 120 tons (Second hand)<br \/>\n<img fetchpriority=\"high\" decoding=\"async\" class=\"alignnone wp-image-1663 size-medium\" src=\"https:\/\/staging.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_3814-300x200.jpeg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_3814-300x200.jpeg 300w, https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_3814.jpeg 640w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/li>\n<\/ul>\n<ul>\n<li>n\u00b0 1 PL95 hydrostatic pipelayer 95 tons (Brand new)<br \/>\n<h3><img decoding=\"async\" class=\"alignnone wp-image-1643 size-medium\" src=\"https:\/\/staging.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_6969-1-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_6969-1-300x225.jpeg 300w, https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_6969-1-768x576.jpeg 768w, https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_6969-1-1024x768.jpeg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h3>\n<\/li>\n<\/ul>\n<ul>\n<li>n\u00b0 1 Farm Tractors Fiat 100\/90 (Second hand)<br \/>\n<h3>\u00a0<img decoding=\"async\" class=\"alignnone wp-image-1648 size-medium\" src=\"https:\/\/staging.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_6960-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_6960-300x225.jpeg 300w, https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_6960-768x576.jpeg 768w, https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_6960-1024x768.jpeg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h3>\n<\/li>\n<\/ul>\n<ul>\n<li>n\u00b0 4 Hydraulic Winch 40 tons (Brand new\/Second Hand)<br \/>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1647 size-medium\" src=\"https:\/\/staging.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_6958-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_6958-300x225.jpeg 300w, https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_6958-768x576.jpeg 768w, https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_6958-1024x768.jpeg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h3>\n<\/li>\n<\/ul>\n<ul>\n<li>n\u00b01 Complete Bending set 24\u201d for 22&#8243;-36\u201d bending machine (Brand new)<br \/>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1650 size-medium\" src=\"https:\/\/staging.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_6963-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_6963-300x225.jpeg 300w, https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_6963-768x576.jpeg 768w, https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_6963-1024x768.jpeg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h3>\n<\/li>\n<\/ul>\n<ul>\n<li>n\u00b0 1 Pneumatic Internal Clamp 28\u201d-30\u201d (Second hand)<\/li>\n<li>n\u00b0 1 Pneumatic Internal Clamp 32\u201d-34&#8243; (Brand new)<br \/>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1646 size-medium\" src=\"https:\/\/staging.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_6957-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_6957-300x225.jpeg 300w, https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_6957-768x576.jpeg 768w, https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/IMG_6957-1024x768.jpeg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h3>\n<\/li>\n<\/ul>\n<ul>\n<li>Selection of external clamps (Brand new)<br \/>\n<h3><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1655 size-medium\" src=\"https:\/\/staging.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/EPE-230-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/EPE-230-300x200.jpg 300w, https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/EPE-230-768x512.jpg 768w, https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/09\/EPE-230-1024x683.jpg 1024w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/h3>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Europipeline Group has always available some pieces of pipeline equipment in stock. Check out the list and see if something matches your site needs! n\u00b0 2 FP120 mechanical pipelayers 120 tons (Second hand) n\u00b0 1 PL95 hydrostatic pipelayer 95 tons (Brand new) n\u00b0 1 Farm Tractors Fiat 100\/90 (Second hand) \u00a0 n\u00b0 4 Hydraulic Winch [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":1488,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.8.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>PIPELINE EQUIPMENT AVAILABLE! - Europipeline Group<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.europipeline-equipment.com\/sito\/pipeline-equipment-available\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PIPELINE EQUIPMENT AVAILABLE! - Europipeline Group\" \/>\n<meta property=\"og:description\" content=\"Europipeline Group has always available some pieces of pipeline equipment in stock. Check out the list and see if something matches your site needs! n\u00b0 2 FP120 mechanical pipelayers 120 tons (Second hand) n\u00b0 1 PL95 hydrostatic pipelayer 95 tons (Brand new) n\u00b0 1 Farm Tractors Fiat 100\/90 (Second hand) \u00a0 n\u00b0 4 Hydraulic Winch [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.europipeline-equipment.com\/sito\/pipeline-equipment-available\/\" \/>\n<meta property=\"og:site_name\" content=\"Europipeline Group\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-23T15:07:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-17T15:02:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2017\/07\/performers980.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1772\" \/>\n\t<meta property=\"og:image:height\" content=\"1181\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"staging-admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"staging-admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.europipeline-equipment.com\/sito\/pipeline-equipment-available\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.europipeline-equipment.com\/sito\/pipeline-equipment-available\/\"},\"author\":{\"name\":\"staging-admin\",\"@id\":\"https:\/\/www.europipeline-equipment.com\/sito\/#\/schema\/person\/16c41e91ae78cd5f73d51db9420d1deb\"},\"headline\":\"PIPELINE EQUIPMENT AVAILABLE!\",\"datePublished\":\"2020-09-23T15:07:36+00:00\",\"dateModified\":\"2021-05-17T15:02:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.europipeline-equipment.com\/sito\/pipeline-equipment-available\/\"},\"wordCount\":85,\"publisher\":{\"@id\":\"https:\/\/www.europipeline-equipment.com\/sito\/#organization\"},\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.europipeline-equipment.com\/sito\/pipeline-equipment-available\/\",\"url\":\"https:\/\/www.europipeline-equipment.com\/sito\/pipeline-equipment-available\/\",\"name\":\"PIPELINE EQUIPMENT AVAILABLE! - Europipeline Group\",\"isPartOf\":{\"@id\":\"https:\/\/www.europipeline-equipment.com\/sito\/#website\"},\"datePublished\":\"2020-09-23T15:07:36+00:00\",\"dateModified\":\"2021-05-17T15:02:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.europipeline-equipment.com\/sito\/pipeline-equipment-available\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.europipeline-equipment.com\/sito\/pipeline-equipment-available\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.europipeline-equipment.com\/sito\/pipeline-equipment-available\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.europipeline-equipment.com\/sito\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PIPELINE EQUIPMENT AVAILABLE!\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.europipeline-equipment.com\/sito\/#website\",\"url\":\"https:\/\/www.europipeline-equipment.com\/sito\/\",\"name\":\"Europipeline Group\",\"description\":\"Europipeline Equipment Design and manufacturing pipewelders, pipelayers, pipe bending machines, pipe holders, line-up clamps, mandrels\",\"publisher\":{\"@id\":\"https:\/\/www.europipeline-equipment.com\/sito\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.europipeline-equipment.com\/sito\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.europipeline-equipment.com\/sito\/#organization\",\"name\":\"Europipeline Equipment Spa\",\"url\":\"https:\/\/www.europipeline-equipment.com\/sito\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.europipeline-equipment.com\/sito\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/06\/ghckbhjnbomccbgc.jpg\",\"contentUrl\":\"https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/06\/ghckbhjnbomccbgc.jpg\",\"width\":562,\"height\":322,\"caption\":\"Europipeline Equipment Spa\"},\"image\":{\"@id\":\"https:\/\/www.europipeline-equipment.com\/sito\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.europipeline-equipment.com\/sito\/#\/schema\/person\/16c41e91ae78cd5f73d51db9420d1deb\",\"name\":\"staging-admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\/\/www.europipeline-equipment.com\/sito\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8b1c336d54c06f4935d6875081e253c1?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8b1c336d54c06f4935d6875081e253c1?s=96&d=mm&r=g\",\"caption\":\"staging-admin\"},\"url\":\"https:\/\/www.europipeline-equipment.com\/sito\/author\/staging-admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PIPELINE EQUIPMENT AVAILABLE! - Europipeline Group","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.europipeline-equipment.com\/sito\/pipeline-equipment-available\/","og_locale":"it_IT","og_type":"article","og_title":"PIPELINE EQUIPMENT AVAILABLE! - Europipeline Group","og_description":"Europipeline Group has always available some pieces of pipeline equipment in stock. Check out the list and see if something matches your site needs! n\u00b0 2 FP120 mechanical pipelayers 120 tons (Second hand) n\u00b0 1 PL95 hydrostatic pipelayer 95 tons (Brand new) n\u00b0 1 Farm Tractors Fiat 100\/90 (Second hand) \u00a0 n\u00b0 4 Hydraulic Winch [&hellip;]","og_url":"https:\/\/www.europipeline-equipment.com\/sito\/pipeline-equipment-available\/","og_site_name":"Europipeline Group","article_published_time":"2020-09-23T15:07:36+00:00","article_modified_time":"2021-05-17T15:02:52+00:00","og_image":[{"width":1772,"height":1181,"url":"https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2017\/07\/performers980.jpg","type":"image\/jpeg"}],"author":"staging-admin","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"staging-admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.europipeline-equipment.com\/sito\/pipeline-equipment-available\/#article","isPartOf":{"@id":"https:\/\/www.europipeline-equipment.com\/sito\/pipeline-equipment-available\/"},"author":{"name":"staging-admin","@id":"https:\/\/www.europipeline-equipment.com\/sito\/#\/schema\/person\/16c41e91ae78cd5f73d51db9420d1deb"},"headline":"PIPELINE EQUIPMENT AVAILABLE!","datePublished":"2020-09-23T15:07:36+00:00","dateModified":"2021-05-17T15:02:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.europipeline-equipment.com\/sito\/pipeline-equipment-available\/"},"wordCount":85,"publisher":{"@id":"https:\/\/www.europipeline-equipment.com\/sito\/#organization"},"articleSection":["News"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/www.europipeline-equipment.com\/sito\/pipeline-equipment-available\/","url":"https:\/\/www.europipeline-equipment.com\/sito\/pipeline-equipment-available\/","name":"PIPELINE EQUIPMENT AVAILABLE! - Europipeline Group","isPartOf":{"@id":"https:\/\/www.europipeline-equipment.com\/sito\/#website"},"datePublished":"2020-09-23T15:07:36+00:00","dateModified":"2021-05-17T15:02:52+00:00","breadcrumb":{"@id":"https:\/\/www.europipeline-equipment.com\/sito\/pipeline-equipment-available\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.europipeline-equipment.com\/sito\/pipeline-equipment-available\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.europipeline-equipment.com\/sito\/pipeline-equipment-available\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.europipeline-equipment.com\/sito\/"},{"@type":"ListItem","position":2,"name":"PIPELINE EQUIPMENT AVAILABLE!"}]},{"@type":"WebSite","@id":"https:\/\/www.europipeline-equipment.com\/sito\/#website","url":"https:\/\/www.europipeline-equipment.com\/sito\/","name":"Europipeline Group","description":"Europipeline Equipment Design and manufacturing pipewelders, pipelayers, pipe bending machines, pipe holders, line-up clamps, mandrels","publisher":{"@id":"https:\/\/www.europipeline-equipment.com\/sito\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.europipeline-equipment.com\/sito\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/www.europipeline-equipment.com\/sito\/#organization","name":"Europipeline Equipment Spa","url":"https:\/\/www.europipeline-equipment.com\/sito\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.europipeline-equipment.com\/sito\/#\/schema\/logo\/image\/","url":"https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/06\/ghckbhjnbomccbgc.jpg","contentUrl":"https:\/\/www.europipeline-equipment.com\/sito\/wp-content\/uploads\/2020\/06\/ghckbhjnbomccbgc.jpg","width":562,"height":322,"caption":"Europipeline Equipment Spa"},"image":{"@id":"https:\/\/www.europipeline-equipment.com\/sito\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.europipeline-equipment.com\/sito\/#\/schema\/person\/16c41e91ae78cd5f73d51db9420d1deb","name":"staging-admin","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.europipeline-equipment.com\/sito\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8b1c336d54c06f4935d6875081e253c1?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b1c336d54c06f4935d6875081e253c1?s=96&d=mm&r=g","caption":"staging-admin"},"url":"https:\/\/www.europipeline-equipment.com\/sito\/author\/staging-admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.europipeline-equipment.com\/sito\/wp-json\/wp\/v2\/posts\/1640"}],"collection":[{"href":"https:\/\/www.europipeline-equipment.com\/sito\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.europipeline-equipment.com\/sito\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.europipeline-equipment.com\/sito\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.europipeline-equipment.com\/sito\/wp-json\/wp\/v2\/comments?post=1640"}],"version-history":[{"count":12,"href":"https:\/\/www.europipeline-equipment.com\/sito\/wp-json\/wp\/v2\/posts\/1640\/revisions"}],"predecessor-version":[{"id":3380,"href":"https:\/\/www.europipeline-equipment.com\/sito\/wp-json\/wp\/v2\/posts\/1640\/revisions\/3380"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.europipeline-equipment.com\/sito\/wp-json\/wp\/v2\/media\/1488"}],"wp:attachment":[{"href":"https:\/\/www.europipeline-equipment.com\/sito\/wp-json\/wp\/v2\/media?parent=1640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.europipeline-equipment.com\/sito\/wp-json\/wp\/v2\/categories?post=1640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.europipeline-equipment.com\/sito\/wp-json\/wp\/v2\/tags?post=1640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}